{"id":17891,"date":"2018-05-06T13:38:40","date_gmt":"2018-05-06T17:38:40","guid":{"rendered":"http:\/\/folhaderondonianews.com\/news\/?p=17891"},"modified":"2018-05-06T17:26:32","modified_gmt":"2018-05-06T21:26:32","slug":"dia-do-desafio-adversario-de-ji-parana-sai-na-2a","status":"publish","type":"post","link":"https:\/\/folhaderondonianews.com\/news\/2018\/05\/06\/dia-do-desafio-adversario-de-ji-parana-sai-na-2a\/","title":{"rendered":"Dia do Desafio: advers\u00e1rio de Ji-Paran\u00e1 sai na 2\u00aa"},"content":{"rendered":"<p>O Dia do Desafio 2018, ser\u00e1 realizado no pr\u00f3ximo 30 de maio. O principal objetivo desta data \u00e9 motivar a popula\u00e7\u00e3o a praticar atividades f\u00edsicas, desenvolver h\u00e1bitos saud\u00e1veis, visando melhorar a sa\u00fade f\u00edsica e mental. Nesta segunda-feira (7) acontece o sorteio entre as cidades participantes.<\/p>\n<p>Em Rond\u00f4nia, segundo informa\u00e7\u00f5es da Fecom\u00e9rcio e do Sesc, que s\u00e3o respons\u00e1veis pela organiza\u00e7\u00e3o do Dia do desafio, o evento vem crescendo a cada ano e, em 2018 haver\u00e1 a participa\u00e7\u00e3o hist\u00f3rica de todos os munic\u00edpios. As 52 cidades do Estado j\u00e1 confirmaram participa\u00e7\u00e3o.<\/p>\n<p>A coordenadora estadual do Dia do Desafio, gerente do Sesc\/Ji-Paran\u00e1 Ilsandra Garcia, comemorou o n\u00famero recorde de participantes, e agradeceu a participa\u00e7\u00e3o das prefeituras. &#8220;Nosso papel \u00e9 mobilizar as autoridades, e consequentemente a popula\u00e7\u00e3o para a pr\u00e1tica esportiva&#8221;, disse Ilsandra.<\/p>\n<p>Na Semana passada, durante o lan\u00e7amento oficial realizado em Ji-Paran\u00e1, os membros das cidades participantes j\u00e1 deram uma amostra do poder de mobiliza\u00e7\u00e3o do Estado. Os professores da Semetur realizaram v\u00e1rias atividades, colocando todos os presentes para se mexer num circuito preparado para o evento.<\/p>\n<p>Ji-Paran\u00e1, que ir\u00e1 participar pelo sexto ano consecutivo, e venceu os \u00faltimos cinco confrontos, est\u00e1 com programa\u00e7\u00e3o e estrat\u00e9gias definidas. A Secret\u00e1ria Municipal de Esportes e Turismo de Ji-Paran\u00e1, Seloi Toti, j\u00e1 vem mantendo reuni\u00f5es com professores de educa\u00e7\u00e3o f\u00edsica, academias, universidades, Secretaria Municipal de Educa\u00e7\u00e3o, empres\u00e1rios, AMT, Policia Rodovi\u00e1ria Federal, Policia Militar, corpo de bombeiros e entidades filantr\u00f3picas, visando mobilizar o maior n\u00famero de pessoas poss\u00edvel. A inten\u00e7\u00e3o \u00e1 atuar em parcerias com os \u00f3rg\u00e3os p\u00fablicos, empresas privadas, universidades e escolas p\u00fablicas e particulares, colocando todos para realizar exerc\u00edcios, adiantou Seloi Totti,.<\/p>\n<p>&#8220;O sucesso do Dia do Desafio depende da participa\u00e7\u00e3o de todos. Cada cidad\u00e3o, sozinho ou em grupo deve praticar pelo menos 15 minutos de atividade f\u00edsica no dia 30 de maio e registrar sua participa\u00e7\u00e3o no telefone (69) 3411-4242\u201d, informou.<\/p>\n<p>O prefeito de Ji-Paran\u00e1, Marcito Pinto (PDT), solicitou o engajamento de todos os \u00f3rg\u00e3os da municipais e aproveitou para destacar os projetos da Secretaria de Esportes, e afirmar que a cidade passa por um momento de transforma\u00e7\u00e3o com escolinhas de inicia\u00e7\u00e3o esportiva em 11 modalidades, ocupando mais de 2.000 alunos no contra-turno escolar.<\/p>\n<p>Marcito agradeceu as parcerias com o Sesc no esporte, cultura e lazer, e firmou o compromisso de continuar as atividades conjuntas que movimentam a segunda maior cidade do Estado de Rond\u00f4nia.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>O principal objetivo desta data \u00e9 motivar a popula\u00e7\u00e3o a praticar atividades f\u00edsicas, desenvolver h\u00e1bitos saud\u00e1veis, visando melhorar a sa\u00fade f\u00edsica e mental. Nesta segunda-feira (7) acontece o sorteio entre as cidades participantes.<\/p>\n<\/div>","protected":false},"author":1,"featured_media":17892,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[3078],"class_list":["post-17891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-dia-do-desafio-2018"],"_links":{"self":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/17891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/comments?post=17891"}],"version-history":[{"count":0,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/17891\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media\/17892"}],"wp:attachment":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media?parent=17891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/categories?post=17891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/tags?post=17891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}