{"id":18290,"date":"2018-05-25T20:54:32","date_gmt":"2018-05-26T00:54:32","guid":{"rendered":"http:\/\/folhaderondonianews.com\/news\/?p=18290"},"modified":"2018-05-29T20:59:42","modified_gmt":"2018-05-30T00:59:42","slug":"confirmada-a-garcon-licitacao-do-transporte-escolar-da-santa-marcelina","status":"publish","type":"post","link":"https:\/\/folhaderondonianews.com\/news\/2018\/05\/25\/confirmada-a-garcon-licitacao-do-transporte-escolar-da-santa-marcelina\/","title":{"rendered":"Confirmado a Lindomar &#8216;Gar\u00e7on&#8217; licita\u00e7\u00e3o do transporte escolar da Santa Marcelina"},"content":{"rendered":"<p>Em audi\u00eancia com o Governador Daniel Pereira, o Deputado Federal Lindomar Gar\u00e7on (PRB-RO) confirmou aos pais dos alunos e \u00e0 diretora da escola Santa Marcelina da BR, Maria de Lourdes Javaro, que dia 15 de junho ser\u00e1 a abertura da licita\u00e7\u00e3o visando a contrata\u00e7\u00e3o da empresa de transporte escolar com monitores, e assim promover melhorias no transporte que atende os alunos da escola Santa Marcelina.<\/p>\n<p>Hoje o transporte escolar fornecido pelo estado, que beneficia pais e alunos, n\u00e3o conta com monitores, s\u00e3o antigos e insuficientes, sempre quebram, atrasando as aulas e consequentemente prejudicando o ano letivo, com isso acredita-se que a terceiriza\u00e7\u00e3o \u00e9 o melhor caminho.<\/p>\n<p>Lindomar Gar\u00e7on na \u00faltima reuni\u00e3o acompanhou uma comiss\u00e3o da dire\u00e7\u00e3o da escola o qual foi parabenizado pelos gestores por trabalhar a muitos anos por esta causa.<\/p>\n<p>Por sua vez, o Parlamentar e a comiss\u00e3o agradeceram ao governador Daniel Pereira e \u00e0 Secret\u00e1ria da Educa\u00e7\u00e3o, Maria Angelica Silvia Ayres, pela presteza que foram recebidos e atendidos com suas reivindica\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Em audi\u00eancia com o Governador Daniel Pereira, o Deputado Federal Lindomar Gar\u00e7on (PRB-RO) confirmou aos pais dos alunos e \u00e0 diretora da escola Santa Marcelina <a class=\"mh-excerpt-more\" href=\"https:\/\/folhaderondonianews.com\/news\/2018\/05\/25\/confirmada-a-garcon-licitacao-do-transporte-escolar-da-santa-marcelina\/\" title=\"Confirmado a Lindomar &#8216;Gar\u00e7on&#8217; licita\u00e7\u00e3o do transporte escolar da Santa Marcelina\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":18291,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cotidiano"],"_links":{"self":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/18290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/comments?post=18290"}],"version-history":[{"count":0,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/18290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media\/18291"}],"wp:attachment":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media?parent=18290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/categories?post=18290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/tags?post=18290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}