{"id":21667,"date":"2019-02-02T16:44:07","date_gmt":"2019-02-02T20:44:07","guid":{"rendered":"http:\/\/folhaderondonianews.com\/news\/?p=21667"},"modified":"2019-02-02T16:44:07","modified_gmt":"2019-02-02T20:44:07","slug":"senadores-decidem-fazer-nova-votacao-para-presidente","status":"publish","type":"post","link":"https:\/\/folhaderondonianews.com\/news\/2019\/02\/02\/senadores-decidem-fazer-nova-votacao-para-presidente\/","title":{"rendered":"Senadores decidem fazer nova vota\u00e7\u00e3o para presidente"},"content":{"rendered":"<p>Ap\u00f3s uma confus\u00e3o na apura\u00e7\u00e3o dos votos para a Presid\u00eancia do Senado, os senadores decidiram repetir a elei\u00e7\u00e3o na tarde de hoje (2). Na hora da apura\u00e7\u00e3o dos votos, foram encontrados 80 envelopes com 80 c\u00e9dulas e outras duas c\u00e9dulas avulsas na urna, o que levantou suspeitas sobre fraude nas elei\u00e7\u00f5es. O total de senadores \u00e9 de 81.<\/p>\n<p>Ap\u00f3s a decis\u00e3o sobre uma nova elei\u00e7\u00e3o, os papeis com os primeiros votos foram triturados.<\/p>\n<p>Antes da elei\u00e7\u00e3o, houve um embate sobre se a vota\u00e7\u00e3o seria aberta ou secreta. Ontem (1\u00ba), ap\u00f3s cinco horas de sess\u00e3o, a maioria dos parlamentares decidiu pelo voto aberto. Mas uma decis\u00e3o do\u00a0<a href=\"http:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2019-02\/toffoli-determina-votacao-secreta-no-senado\" target=\"_blank\" rel=\"noopener\">presidente do Supremo Tribunal Federal (STF), Dias Toffoli<\/a>\u00a0determinou que a vota\u00e7\u00e3o deveria ser secreta.<\/p>\n<p>Seis senadores concorrem \u00e0 Presid\u00eancia do Senado: \u00c2ngelo Coronel (PSD-BA), Davi Alcolumbre (DEM-AP), Espiridi\u00e3o Amin (PP-SC), Fernando Collor (Pros-AL), Renan Calheiros (MDB-AL), Reguffe (sem partido-DF).<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Ap\u00f3s uma confus\u00e3o na apura\u00e7\u00e3o dos votos para a Presid\u00eancia do Senado, os senadores decidiram repetir a elei\u00e7\u00e3o na tarde de hoje (2). Na hora <a class=\"mh-excerpt-more\" href=\"https:\/\/folhaderondonianews.com\/news\/2019\/02\/02\/senadores-decidem-fazer-nova-votacao-para-presidente\/\" title=\"Senadores decidem fazer nova vota\u00e7\u00e3o para presidente\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":21668,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[1006],"class_list":["post-21667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-senado"],"_links":{"self":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/21667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/comments?post=21667"}],"version-history":[{"count":0,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/21667\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media\/21668"}],"wp:attachment":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media?parent=21667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/categories?post=21667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/tags?post=21667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}