{"id":27957,"date":"2020-04-24T09:37:22","date_gmt":"2020-04-24T13:37:22","guid":{"rendered":"https:\/\/folhaderondonianews.com\/news\/?p=27957"},"modified":"2020-04-25T10:00:13","modified_gmt":"2020-04-25T14:00:13","slug":"ji-parana-registra-26-casos-de-covid-19","status":"publish","type":"post","link":"https:\/\/folhaderondonianews.com\/news\/2020\/04\/24\/ji-parana-registra-26-casos-de-covid-19\/","title":{"rendered":"Ji-Paran\u00e1 registra 26 casos de Covid-19"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: left;\" align=\"center\">A Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Sa\u00fade (Semusa), torna p\u00fablico que o munic\u00edpio de Ji-Paran\u00e1 registrou, nesta sexta-feira (24), mais 14 casos de Covid-19. Os casos foram confirmados por\u00a0<b>crit\u00e9rio cl\u00ednico-epidemiol\u00f3gico<\/b>, ou seja, ainda sem a confirma\u00e7\u00e3o por exames laboratoriais.<\/p>\n<p class=\"x_MsoNormal\">A confirma\u00e7\u00e3o, neste caso, ocorreu pelo fato desses pacientes apresentarem sintomas leves e hist\u00f3rico de contato pr\u00f3ximo ou domiciliar, nos \u00faltimos 7 dias, com os cinco pacientes que tiveram confirma\u00e7\u00e3o laboratorial para Covid-19 no dia de ontem (23). Todos esses pacientes est\u00e3o em isolamento domiciliar e com quadro de sa\u00fade est\u00e1vel.<\/p>\n<p class=\"x_MsoNormal\">Os casos notificados referem-se a:<\/p>\n<p class=\"x_MsoNormal\"><b>10 pacientes do sexo feminino, com idades de 07, 41, 25, 37, 31, 61, 44, 27, 42, 46 anos.<\/b><\/p>\n<p class=\"x_MsoNormal\"><b>\u00a0<\/b><b>04 pacientes do sexo masculino, com idades de 62, 45, 37, 34 anos.<\/b><\/p>\n<p class=\"x_MsoNormal\">Com as informa\u00e7\u00f5es emitidas hoje (24), pelo Departamento de Vigil\u00e2ncia em Sa\u00fade, a cidade de Ji-Paran\u00e1 apresenta:<\/p>\n<p class=\"x_MsoNormal\"><b>26\u2013 confirmados<\/b><\/p>\n<p class=\"x_MsoNormal\">12- confirmados por exames<\/p>\n<p class=\"x_MsoNormal\">14 \u2013 confirmados por crit\u00e9rio cl\u00ednico-epidemiol\u00f3gico<\/p>\n<p class=\"x_MsoNormal\">02 &#8211; Curados<\/p>\n<p class=\"x_MsoNormal\">02 \u2013 \u00d3bitos<\/p>\n<p class=\"x_MsoNormal\">02 &#8211; Internados<\/p>\n<p class=\"x_MsoNormal\">20 \u2013 Em isolamento domiciliar com sintomas leves<\/p>\n<p class=\"x_MsoNormal\">59 &#8211; Casos suspeitos<\/p>\n<p class=\"x_MsoNormal\">142 &#8211; Descartados<\/p>\n<p class=\"x_MsoNormal\">Para maiores esclarecimentos, o Secret\u00e1rio Municipal de Sa\u00fade, Rafael Papa, estar\u00e1 \u00e0 disposi\u00e7\u00e3o dos profissionais de imprensa com a costumeira aten\u00e7\u00e3o.<\/p>\n<p class=\"x_MsoNormal\">\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>A Prefeitura de Ji-Paran\u00e1, por meio da Secretaria Municipal de Sa\u00fade (Semusa), torna p\u00fablico que o munic\u00edpio de Ji-Paran\u00e1 registrou, nesta sexta-feira (24), mais 14 <a class=\"mh-excerpt-more\" href=\"https:\/\/folhaderondonianews.com\/news\/2020\/04\/24\/ji-parana-registra-26-casos-de-covid-19\/\" title=\"Ji-Paran\u00e1 registra 26 casos de Covid-19\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":27961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-27957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/27957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/comments?post=27957"}],"version-history":[{"count":0,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/27957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media\/27961"}],"wp:attachment":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media?parent=27957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/categories?post=27957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/tags?post=27957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}