{"id":4379,"date":"2015-01-19T16:58:50","date_gmt":"2015-01-19T20:58:50","guid":{"rendered":"http:\/\/folhaderondonianews.com\/news\/?p=4379"},"modified":"2015-01-19T16:58:50","modified_gmt":"2015-01-19T20:58:50","slug":"olhe-para-o-ceu-em-2015-ano-repleto-de-fenomenos-astronomicos-visiveis-a-olho-nu","status":"publish","type":"post","link":"https:\/\/folhaderondonianews.com\/news\/2015\/01\/19\/olhe-para-o-ceu-em-2015-ano-repleto-de-fenomenos-astronomicos-visiveis-a-olho-nu\/","title":{"rendered":"Olhe para o c\u00e9u em 2015 &#8211; Ano repleto de fen\u00f4menos astron\u00f4micos vis\u00edveis a olho nu"},"content":{"rendered":"<p><strong>(<\/strong><strong><em>Tiberius Drumond) \u00a0&#8211;\u00a0<\/em><\/strong>O ano de 2015 trar\u00e1 \u00f3timas oportunidades para admirar o c\u00e9u \u00e0 noite, prato cheio para quem tem luneta ou telesc\u00f3pio em casa. Mas se voc\u00ea n\u00e3o tem esses equipamentos, n\u00e3o se preocupe. Haver\u00e1 fen\u00f4menos astron\u00f4micos que poder\u00e3o ser facilmente observados a olho nu no Brasil. Para n\u00e3o perd\u00ea-los de vista, fique atento \u00e0s dicas do professor Jair Barroso, pesquisador do Observat\u00f3rio Nacional e colaborador da Olimp\u00edada Brasileira de Astronomia e Astron\u00e1utica (OBA).<\/p>\n<p>Segundo o astr\u00f4nomo, logo no come\u00e7o de fevereiro, ser\u00e1 poss\u00edvel identificar com facilidade o maior planeta do sistema solar: J\u00fapiter. Um dos mais brilhantes do c\u00e9u noturno, o planeta apresenta, em geral, um tom ligeiramente amarelado.<\/p>\n<p>&#8211; A oposi\u00e7\u00e3o de J\u00fapiter se dar\u00e1 em 6 de fevereiro, quando ocorrer\u00e1 o\u00a0alinhamento: Sol-Terra-J\u00fapiter. Isso permitir\u00e1 que ele chame bastante a aten\u00e7\u00e3o dos observadores, pois ser\u00e1 vis\u00edvel durante quase toda a noite. Al\u00e9m disso, no dia 3, ele estar\u00e1 em conjun\u00e7\u00e3o com a Lua. Ou seja, &#8220;pr\u00f3ximo&#8221; ao nosso sat\u00e9lite natural, ajudando ainda mais na sua identifica\u00e7\u00e3o &#8211; revela.<\/p>\n<p>Barroso diz que em fevereiro ser\u00e1 poss\u00edvel ver outro planeta conhecido: Saturno. Famoso pelos seus an\u00e9is, o astro poder\u00e1 ser visto de madrugada, no lado nascente, na constela\u00e7\u00e3o do Escorpi\u00e3o.\u00a0\u201cE em 13 de fevereiro, antes de clarear o dia, a Lua vai compor com o planeta e a estrela Antares (o cora\u00e7\u00e3o do Escorpi\u00e3o) um belo tri\u00e2ngulo no c\u00e9u\u201d.<\/p>\n<p>&#8211; Para facilitar a identifica\u00e7\u00e3o, Antares estar\u00e1 \u00e0 direita da Lua. E Saturno vai estar acima. Essa posi\u00e7\u00e3o vai valer praticamente para todo o Brasil. Ao visualizar o fen\u00f4meno, seguindo as estrelas \u00e0 direita da Lua e de Saturno, ser\u00e1 poss\u00edvel observar facilmente a forma estilizada do Escorpi\u00e3o &#8211; diz.<\/p>\n<p>Outro acontecimento com boa visibilidade envolver\u00e1 V\u00eanus, conhecido como Vesper, no poente, ap\u00f3s o p\u00f4r do Sol, ou como Estrela Dalva, devido \u00e0 sua apari\u00e7\u00e3o no leste, antes do nascer do Sol. Jair explica que no momento o planeta vem saindo de tr\u00e1s do Sol. Mas o seu afastamento vem aumentando progressivamente, tornando-o facilmente vis\u00edvel em breve. \u201cNo dia 6 de junho, teremos sua elonga\u00e7\u00e3o m\u00e1xima (maior \u00e2ngulo Terra-Sol-V\u00eanus) nessa temporada, 45\u00b0, no poente, o que favorecer\u00e1 a sua observa\u00e7\u00e3o\u201d.<\/p>\n<p>Mas n\u00e3o s\u00f3 de planetas ou cometas vivem os belos fen\u00f4menos astron\u00f4micos. De acordo com Barroso, a Lua, em seu passeio mensal pelo zod\u00edaco, sempre reserva \u00f3timas situa\u00e7\u00f5es para observa\u00e7\u00e3o, como, por exemplo, conjun\u00e7\u00f5es com importantes estrelas. Uma delas se dar\u00e1 com a gigante vermelha Aldebaran, a mais brilhante da constela\u00e7\u00e3o do Touro. Nosso sat\u00e9lite passar\u00e1 no final de janeiro, a 29, bem &#8220;perto&#8221; dela no c\u00e9u no lado norte, vis\u00edvel j\u00e1 ao escurecer.<\/p>\n<p>&#8211; Tamb\u00e9m conseguiremos ver as chamadas \u201cTr\u00eas Marias\u201d, que formam o cintur\u00e3o de \u00d3rion, olhando nas proximidades da conjun\u00e7\u00e3o acima. Por meio desses eventos, as pessoas poder\u00e3o conhecer melhor o desenho de conhecidas constela\u00e7\u00f5es, ao menos suas estrelas principais \u2013 sugere.<\/p>\n<p>O astr\u00f4nomo diz ainda que no dia 28 de setembro acontecer\u00e1 um eclipse lunar total. Isso acontece quando a Lua \u201cpassa\u201d pela sombra do nosso planeta no espa\u00e7o, chamada de umbra.<\/p>\n<p>&#8211; Nessa regi\u00e3o, ela recebe somente a luz refratada e filtrada pela atmosfera terrestre proveniente do Sol. Isso d\u00e1 ao nosso sat\u00e9lite, em boa parte dos eclipses, uma tonalidade avermelhada, de forma mais ou menos acentuada conforme a composi\u00e7\u00e3o de nossa atmosfera na ocasi\u00e3o &#8211; explica.<\/p>\n<p>Barroso sugere que as pessoas tentem observar o c\u00e9u noturno e se familiarizem com sua apar\u00eancia. Isso ajuda a entender como os astros se movimentam. \u201cSempre que poss\u00edvel, acompanhe esses acontecimentos nos dias anteriores e posteriores a eventos e repare o quanto os astros se deslocam. \u00c9 um \u00f3timo exerc\u00edcio para mente e um \u2018col\u00edrio\u2019 para os olhos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>(Tiberius Drumond) \u00a0&#8211;\u00a0O ano de 2015 trar\u00e1 \u00f3timas oportunidades para admirar o c\u00e9u \u00e0 noite, prato cheio para quem tem luneta ou telesc\u00f3pio em casa. <a class=\"mh-excerpt-more\" href=\"https:\/\/folhaderondonianews.com\/news\/2015\/01\/19\/olhe-para-o-ceu-em-2015-ano-repleto-de-fenomenos-astronomicos-visiveis-a-olho-nu\/\" title=\"Olhe para o c\u00e9u em 2015 &#8211; Ano repleto de fen\u00f4menos astron\u00f4micos vis\u00edveis a olho nu\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4379","post","type-post","status-publish","format-standard","hentry","category-coluna-do-gutierrez"],"_links":{"self":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/4379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/comments?post=4379"}],"version-history":[{"count":0,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/posts\/4379\/revisions"}],"wp:attachment":[{"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/media?parent=4379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/categories?post=4379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/folhaderondonianews.com\/news\/wp-json\/wp\/v2\/tags?post=4379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}